{"id":101,"count":0,"description":"Todos los grifos de lavabo est\u00e1n dise\u00f1ados pensando en la seguridad. La elegante manija de control permite a las personas controlar f\u00e1cilmente la temperatura adecuada del agua. La fina v\u00e1lvula de lat\u00f3n garantiza miles de veces de uso. Hay muchas opciones de dise\u00f1os de grifos que se adaptan a varios tipos de lavabos y decoraci\u00f3n, lo que hace que su hermosa casa sea m\u00e1s delicada.","link":"https:\/\/ghgalaxyhome.com\/es\/products-40777","name":"Grifo de lavabo","slug":"products-40777","taxonomy":"product_cat","parent":24,"meta":[],"_links":{"self":[{"href":"https:\/\/ghgalaxyhome.com\/es\/wp-json\/wp\/v2\/product_cat\/101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ghgalaxyhome.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/ghgalaxyhome.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/ghgalaxyhome.com\/es\/wp-json\/wp\/v2\/product_cat\/24"}],"wp:post_type":[{"href":"https:\/\/ghgalaxyhome.com\/es\/wp-json\/wp\/v2\/product?product_cat=101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}